{"id":11658,"date":"2026-02-11T17:58:14","date_gmt":"2026-02-11T09:58:14","guid":{"rendered":"https:\/\/silagebaler.com\/?p=11658"},"modified":"2026-02-12T11:25:23","modified_gmt":"2026-02-12T03:25:23","slug":"vertical-tmr-mixer-silage-feed-mixer","status":"publish","type":"post","link":"https:\/\/silagebaler.com\/de\/vertical-tmr-mixer-silage-feed-mixer\/","title":{"rendered":"Vertikaler TMR-Mischer"},"content":{"rendered":"<p class=\"wp-block-paragraph translation-block\">Taizy <strong>vertikaler TMR-Mischer<\/strong> ist eine Futtermischvorrichtung, die Silage, Heu, Stroh, Konzentrate, Mineralzus\u00e4tze und andere Zutaten in genauen Anteilen durch ein vertikales Schraubenmischsystem gr\u00fcndlich vermischt. Er bietet eine breite Kapazit\u00e4t von 3-36 m\u00b3, kraftvolles Schneiden von langfaserigem Material und verhindert, dass Rinder selektiv fressen, was die Futterausnutzung verbessert.<\/p>    <p class=\"wp-block-paragraph\">Daher wird dieser TMR-Futtermischer h\u00e4ufig in Milchkuh-, Rinder-, Schafbetrieben usw. eingesetzt. F\u00fcr Betriebe, die standardisierte F\u00fctterungssysteme einrichten, ist der TMR-Mischwagen ein Schl\u00fcsselger\u00e4t zur Steigerung der Produktionseffizienz.<\/p>    <figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"Vertical TMR Feed Mixer Working Video | Cattle &amp; Livestock Feed Mixing Machine\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rea_cVUF8us?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div><\/figure>    <h2 class=\"wp-block-heading\"><strong>Vorteile des Taizy vertikalen TMR-Mischers<\/strong><\/h2>    <ul class=\"wp-block-list\"> <li>Legierungsverschlei\u00dffeste Klingen f\u00fcr \u00fcberlegene Schneidleistung <ul class=\"wp-block-list\"> <li>Vertikale Spiralbl\u00e4tter zerkleinern effektiv Stroh- und Silagefasern und verbessern die Verdaulichkeit.<\/li> <\/ul> <\/li>    <li>Verstellbares Entladeventildesign<\/li>    <li>Geringere Investitionskosten <ul class=\"wp-block-list\"> <li>Die vertikale Ausr\u00fcstung zeichnet sich durch einfachere Konstruktion und h\u00f6here Kosteneffizienz aus.<\/li> <\/ul> <\/li>    <li>Kompakte Grundfl\u00e4che <ul class=\"wp-block-list\"> <li>Ideal f\u00fcr kleine bis mittlere Betriebe und Erweiterungsprojekte.<\/li> <\/ul> <\/li>    <li>Verst\u00e4rkte Stahlplattenkonstruktion f\u00fcr l\u00e4ngere Lebensdauer<\/li>    <li>Gleichm\u00e4\u00dfigere Mischung <ul class=\"wp-block-list\"> <li>Verhindert effektiv das Sortieren des Futters und sorgt f\u00fcr ausgewogene Ern\u00e4hrung bei jedem Bissen.<\/li> <\/ul> <\/li>    <li>Anpassungsunterst\u00fctzung <ul class=\"wp-block-list\"> <li>Spannung: 380V \/ 400V \/ 415V usw.<\/li>    <li>Maschinenfarbe: Hellgr\u00fcn, unscharf, rot oder andere<\/li> <\/ul> <\/li>    <li>Optionale Konfigurationen <ul class=\"wp-block-list\"> <li>TMR-Mischer mit Wiegesystem<\/li>    <li>Hydraulischer Futterautomat<\/li>    <li>Motortypen: Elektromotor, Dieselmotor, PTO<\/li>    <li>F\u00f6rderband f\u00fcr gemischtes TMR-Futter<\/li>    <li>Maschinenreifen<\/li>    <li>Dreir\u00e4der, die zum Transport des TMR-Futtermischers verwendet werden<\/li> <\/ul> <\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11717\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-silage-feed-mixing-machine.webp\" alt=\"Vertikaler Futtermischwagen\" class=\"wp-image-11717\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-silage-feed-mixing-machine.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-silage-feed-mixing-machine-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-silage-feed-mixing-machine-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">7 cbm Silage-Futtermischmaschine<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11716\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon.webp\" alt=\"vertical feed mixer wagon\" class=\"wp-image-11716\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Vertikaler Futtermischwagen<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\"><strong>Verschiedene Modelle von TMR-Futtermischern<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Der Standard-vertikale TMR-Mischer ist station\u00e4r und fest installiert.<\/p>    <p class=\"wp-block-paragraph\">As the silage market continues to develop, based on the diverse needs of our clients&#8217; farms, we have continuously researched and developed the following silage mixer wagon types:<\/p>    <h3 class=\"wp-block-heading\"><strong>Modell 1: Elektrischer Typ mit Entladef\u00f6rderband<\/strong><\/h3>    <p class=\"wp-block-paragraph\">Dieses station\u00e4re Futtermischger\u00e4t nutzt einen Elektromotor als Antrieb und arbeitet mit einem F\u00f6rderband f\u00fcr bequemes Entladen.<\/p>    <ul class=\"wp-block-list\"> <li>Geeignet f\u00fcr: <ul class=\"wp-block-list\"> <li>Feste Weiden mit stabiler Drehstromversorgung<\/li>    <li>Kostenbewusste Nutzer<\/li>    <li>Kleine bis mittlere Milchviehbetriebe<\/li> <\/ul> <\/li>    <li>Merkmale: <ul class=\"wp-block-list\"> <li>Stabiler Betrieb<\/li>    <li>Geringe Wartungskosten<\/li>    <li>Einfache und langlebige Konstruktion<\/li> <\/ul> <\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"11714\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-tmr-feed-mixer-with-discharging-conveyor-belt.webp\" alt=\"vertical tmr feed mixer with discharging conveyor belt\" class=\"wp-image-11714\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-tmr-feed-mixer-with-discharging-conveyor-belt.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-tmr-feed-mixer-with-discharging-conveyor-belt-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-tmr-feed-mixer-with-discharging-conveyor-belt-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-tmr-feed-mixer-with-discharging-conveyor-belt-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Vertikaler TMR-Futtermischer mit Entladef\u00f6rderband<\/figcaption><\/figure>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"11715\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/animal-feed-blender-for-diary-farm.webp\" alt=\"animal feed blender for diary farm\" class=\"wp-image-11715\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/animal-feed-blender-for-diary-farm.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/animal-feed-blender-for-diary-farm-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/animal-feed-blender-for-diary-farm-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/animal-feed-blender-for-diary-farm-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Tierfuttermischer f\u00fcr Milchviehbetriebe<\/figcaption><\/figure> <\/figure>    <h3 class=\"wp-block-heading\"><strong>Modell 2: Elektrischer TMR-Futtermischer mit hydraulischer Beladung<\/strong><\/h3>    <p class=\"wp-block-paragraph\">Im Gegensatz zum vorherigen Modell verf\u00fcgt dieser vertikale TMR-Mischer \u00fcber eine hydraulische Beladung.<\/p>    <ul class=\"wp-block-list\"> <li>Geeignet f\u00fcr: <ul class=\"wp-block-list\"> <li>Gro\u00dfbetriebe<\/li>    <li>Regionen mit hohen Arbeitskosten<\/li>    <li>Milchviehbetriebe mit Fokus auf Effizienz<\/li> <\/ul> <\/li>    <li>Merkmale: <ul class=\"wp-block-list\"> <li>Automatisches Beladen<\/li>    <li>Arbeitsersparnis<\/li>    <li>Verbesserte t\u00e4gliche F\u00fctterungseffizienz<\/li> <\/ul> <\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"11719\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tmr-vertical-feed-mixer-with-hydraulic-loading.webp\" alt=\"tmr vertical feed mixer with hydraulic loading\" class=\"wp-image-11719\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tmr-vertical-feed-mixer-with-hydraulic-loading.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tmr-vertical-feed-mixer-with-hydraulic-loading-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tmr-vertical-feed-mixer-with-hydraulic-loading-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tmr-vertical-feed-mixer-with-hydraulic-loading-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">TMR vertikaler Futtermischer mit hydraulischer Beladung<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"11720\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-with-hydraulic-feeder.webp\" alt=\"vertical feed mixer wagon with hydraulic feeder\" class=\"wp-image-11720\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-with-hydraulic-feeder.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-with-hydraulic-feeder-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-with-hydraulic-feeder-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/vertical-feed-mixer-wagon-with-hydraulic-feeder-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Vertikaler Futtermischwagen mit hydraulischem Futterautomat<\/figcaption><\/figure> <\/figure>    <h3 class=\"wp-block-heading\"><strong>Modell 3: PTO-getriebener TMR-Mischer<\/strong><\/h3>    <p class=\"wp-block-paragraph\">Diese Art des vertikalen TMR-Mischers nutzt einen Traktor als Antrieb. Er kann mit Reifen ausgestattet werden, um vorw\u00e4rts zu bewegen.<\/p>    <ul class=\"wp-block-list\"> <li>Geeignet f\u00fcr: <ul class=\"wp-block-list\"> <li>Traktoreigent\u00fcmer<\/li>    <li>Gebiete ohne feste Stromversorgung<\/li>    <li>Betriebe, die mobile F\u00fctterung ben\u00f6tigen<\/li> <\/ul> <\/li>    <li>Hauptmerkmale: <ul class=\"wp-block-list\"> <li>Direktanschluss an den Traktor<\/li>    <li>Flexible Bedienung<\/li>    <li>Besonders geeignet f\u00fcr afrikanische und s\u00fcdostasiatische M\u00e4rkte<\/li> <\/ul> <\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11724\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tractor-driven-grass-mixer-wagon.webp\" alt=\"tractor-driven grass mixer wagon\" class=\"wp-image-11724\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tractor-driven-grass-mixer-wagon.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tractor-driven-grass-mixer-wagon-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/tractor-driven-grass-mixer-wagon-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Traktorgetriebener Gras-Mischwagen<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11723\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/PTO-forage-feed-mixer.webp\" alt=\"PTO forage feed mixer\" class=\"wp-image-11723\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/PTO-forage-feed-mixer.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/PTO-forage-feed-mixer-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/PTO-forage-feed-mixer-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">PTO-Futterautomat<\/figcaption><\/figure> <\/figure>    <h3 class=\"wp-block-heading\"><strong>Modell 4: Dieselbetriebener TMR-Silage-Mischer<\/strong><\/h3>    <p class=\"wp-block-paragraph\">Es handelt sich um einen dieselbetriebenen Futtermischer, der das Problem unzureichender Leistung l\u00f6st.<\/p>    <ul class=\"wp-block-list\"> <li>Geeignet f\u00fcr: <ul class=\"wp-block-list\"> <li>In abgelegenen Gebieten<\/li>    <li>Regionen mit instabiler Stromversorgung<\/li>    <li>Afrikanische und Nahost-M\u00e4rkte<\/li> <\/ul> <\/li>    <li>Hauptmerkmale: <ul class=\"wp-block-list\"> <li>Unabh\u00e4ngige Energiequelle<\/li>    <li>Hohe Anpassungsf\u00e4higkeit<\/li>    <li>Stabiler und zuverl\u00e4ssiger Betrieb<\/li> <\/ul> <\/li> <\/ul>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11726\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-12cbm-animal-feed-mixer.webp\" alt=\"diesel-powered 12cbm animal feed mixer\" class=\"wp-image-11726\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-12cbm-animal-feed-mixer.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-12cbm-animal-feed-mixer-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-12cbm-animal-feed-mixer-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Dieselbetriebener 12 cbm Tierfuttermischer<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"11727\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-tmr-feed-mixer-with-truck.webp\" alt=\"diesel-powered tmr feed mixer with truck\" class=\"wp-image-11727\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-tmr-feed-mixer-with-truck.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-tmr-feed-mixer-with-truck-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-tmr-feed-mixer-with-truck-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/diesel-powered-tmr-feed-mixer-with-truck-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">Dieselbetriebener TMR-Futtermischer mit LKW<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\"><strong>Technische Parameter des station\u00e4ren vertikalen TMR-Mischwagens<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Nach Durchsicht des oben Gesagten sollten Sie verstehen, dass unsere vertikalen Silage-Futtermischer in verschiedenen Konfigurationen erh\u00e4ltlich sind. Hier pr\u00e4sentieren wir das Standardmodell zur Kundenreferenz. Wenn Sie die spezifischen Parameter eines bestimmten Modells wissen m\u00f6chten, kontaktieren Sie uns bitte.<\/p>    <figure class=\"wp-block-table\"><table><tbody><tr><td>Modell<\/td><td>9JGL-5<\/td><td>9JGL-7<\/td><td>9JGL-9<\/td><td>9JGL-12<\/td><td>9JGL-15<\/td><td>9JGL-18<\/td><td>9JGL-24<\/td><td>9JGL-36<\/td><\/tr><tr><td>Volumen (m\u00b3)<\/td><td>5<\/td><td>7<\/td><td>8<\/td><td>12<\/td><td>15<\/td><td>18<\/td><td>24<\/td><td>36<\/td><\/tr><tr><td>Gr\u00f6\u00dfe (mm)<\/td><td>3400*2100*2100<\/td><td>3500*2200*2350<\/td><td>3800*2200*2450<\/td><td>4000*2250*2700<\/td><td>5200*2500*2180<\/td><td>6100*2400*2700<\/td><td>6800*2500*3000<\/td><td>8300*3350*2650<\/td><\/tr><tr><td>Futtereingang Gr\u00f6\u00dfe (mm)<\/td><td>2400*1800<\/td><td>2800*2100<\/td><td>2800*2100<\/td><td>3200*2200<\/td><td>\/<\/td><td>\/<\/td><td>5700*2200<\/td><td>\/<\/td><\/tr><tr><td>Ausgangsnummer (St\u00fcck)<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>\/<\/td><td>1<\/td><td>\/<\/td><td>2<\/td><\/tr><tr><td>Leistung (kW)<\/td><td>18.5<\/td><td>22<\/td><td>30<\/td><td>37<\/td><td>2&#215;22<\/td><td>2&#215;30<\/td><td>2&#215;37<\/td><td>3&#215;37<\/td><\/tr><tr><td>Ausgang (kg\/h)<\/td><td>\/<\/td><td>2500-3500<\/td><td>3000-4000<\/td><td>4000-4500<\/td><td>15-20\/min pro Charge<\/td><td>6000-10000<\/td><td>\/<\/td><td>\/<\/td><\/tr><tr><td>Gro\u00dfe dreieckige Klingen (St\u00fcck)<\/td><td>5<\/td><td>7<\/td><td>8<\/td><td>9<\/td><td>\/<\/td><td>\/<\/td><td>20<\/td><td>\/<\/td><\/tr><tr><td>Kleine Klingen (St\u00fcck)<\/td><td>4<\/td><td>6<\/td><td>7<\/td><td>8<\/td><td>\/<\/td><td>\/<\/td><td>12<\/td><td>\/<\/td><\/tr><tr><td>Feste Klingen (St\u00fcck)<\/td><td>2<\/td><td>2<\/td><td>2<\/td><td>2<\/td><td>2<\/td><td>\/<\/td><td>2<\/td><td>\/<\/td><\/tr><tr><td>W\u00e4gesystem (Set)<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>1<\/td><td>3 (rundf\u00f6rmige)<\/td><td>1<\/td><\/tr><tr><td>Hauptwellen-Drehzahl (U\/min)<\/td><td>23<\/td><td>23<\/td><td>23<\/td><td>23<\/td><td>2323<\/td><td>23<\/td><td>23<\/td><td>\/<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Spezifikationen des festen vertikalen TMR-Futtermischers<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\"><strong>Kapazit\u00e4tsoptionen des vertikalen TMR-Mischers<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Wir bieten mehrere Kapazit\u00e4tsangaben, um den Bed\u00fcrfnissen verschiedener Ranchgr\u00f6\u00dfen gerecht zu werden. Nachfolgend sind empfohlene Ger\u00e4tekapazit\u00e4ten basierend auf der Herdenzahl f\u00fcr Ihre Referenz aufgef\u00fchrt.<\/p>    <figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Kapazit\u00e4t<\/td><td>Geeignete Farmgr\u00f6\u00dfe<\/td><\/tr><tr><td>3\u20135 m\u00b3<\/td><td>50\u2013100 Tiere<\/td><\/tr><tr><td>6\u201310 m\u00b3<\/td><td>100\u2013300 Tiere<\/td><\/tr><tr><td>12\u201325 m\u00b3, noch gr\u00f6\u00dfer<\/td><td>Gro\u00dfe Betriebe mit \u00fcber 300 Tieren<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Referenzliste f\u00fcr Silage-Futtermischer-Kapazit\u00e4tsauswahl<\/figcaption><\/figure>    <p class=\"wp-block-paragraph\">Die Auswahl der geeigneten Kapazit\u00e4t hilft, \u00dcberinvestitionen zu vermeiden und gleichzeitig effiziente t\u00e4gliche F\u00fctterungsprozesse sicherzustellen.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11731\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-feed-mixer-machine.webp\" alt=\"15 cbm Silage-Futtermischer\" class=\"wp-image-11731\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-feed-mixer-machine.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-feed-mixer-machine-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/7cbm-feed-mixer-machine-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">7 cbm Futtermischer<\/figcaption><\/figure>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11733\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/15cbm-silage-feed-mixer.webp\" alt=\"20 cbm TMR-Futtermischwagen\" class=\"wp-image-11733\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/15cbm-silage-feed-mixer.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/15cbm-silage-feed-mixer-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/15cbm-silage-feed-mixer-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">15 cbm Silage-Futtermischer<\/figcaption><\/figure> <\/figure>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"819\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer.webp\" alt=\"20 cbm TMR-Futtermischer\" class=\"wp-image-11738\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer.webp 1020w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-600x482.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-300x241.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-768x617.webp 768w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-15x12.webp 15w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption class=\"wp-element-caption\">20 cbm TMR-Futtermischer<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\"><strong>Anwendung des vertikalen Silage-Futtermischwagens<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Dieses Silagemischger\u00e4t ist speziell f\u00fcr Silagefutter konzipiert und verarbeitet effizient:<\/p>    <ul class=\"wp-block-list\"> <li>Mais-Silage<\/li>    <li>Heu<\/li>    <li>Stroh<\/li>    <li>Konzentrate<\/li> <\/ul>    <p class=\"wp-block-paragraph\">Durch die Einrichtung eines standardisierten TMR-F\u00fctterungssystems mit dem Taizy vertikalen TMR-Mischer k\u00f6nnen Sie erreichen:<\/p>    <ul class=\"wp-block-list\"> <li>Steigerung der Milchproduktion<\/li>    <li>Verbesserter Gewichtszuwachs bei Rindern<\/li>    <li>Reduzierter Futterverlust<\/li>    <li>Verbesserte Herdengesundheit<\/li> <\/ul>    <p class=\"wp-block-paragraph\">F\u00fcr moderne Milchviehbetriebe ist die Investition in einen hochwertigen Rindermischer eine entscheidende Garantie f\u00fcr langfristige Rentabilit\u00e4t.<\/p>    <h2 class=\"wp-block-heading\"><strong>Wie w\u00e4hlt man den richtigen vertikalen TMR-Mischer f\u00fcr Silagefutter?\ufffc<\/strong><\/h2>    <p class=\"wp-block-paragraph\">Bei der Auswahl von Mischanlagen ber\u00fccksichtigen Kunden h\u00e4ufig den Preis des TMR-Mischers, PTO- oder Elektromodell sowie die Anwendungsstoffe. Basierend auf umfangreicher Erfahrung empfehlen wir Kunden, Folgendes zu beachten:<\/p>    <ul class=\"wp-block-list\"> <li>Wie gro\u00df ist Ihre Herde?\ufffc<\/li>    <li>Haben Sie eine stabile Stromversorgung?\ufffc<\/li>    <li>Besitzen Sie bereits einen Traktor?\ufffc<\/li>    <li>Ben\u00f6tigen Sie hydraulisches automatisches F\u00fcttern?\ufffc<\/li>    <li>Wie oft am Tag f\u00fcttern Sie?\ufffc<\/li> <\/ul>    <p class=\"wp-block-paragraph\">Basierend auf diesen Fragen k\u00f6nnen wir das passende vertikale TMR-Futtermischmodell genau zuordnen.<\/p>    <h2 class=\"wp-block-heading\"><strong>Erfolgsfall: TMR-Silage-Mischer f\u00fcr weltweite Kunden<\/strong><\/h2>    <p class=\"wp-block-paragraph translation-block\"><strong>PTO-getriebener TMR-Mischer f\u00fcr wachsenden Rinderbetrieb in Kenia<\/strong><\/p>    <p class=\"wp-block-paragraph\">Der kenianische Kunde besitzt einen eigenen Traktor, hat aber keine stabile Drehstromversorgung und entscheidet sich daher f\u00fcr einen PTO-TMR-Mischer.<\/p>    <p class=\"wp-block-paragraph\">Wir haben einen speziell f\u00fcr die Mischung von Maissilage und Stroh ausgelegten 6 m\u00b3 Traktor-getriebenen Futtermischer konfiguriert.<\/p>    <p class=\"wp-block-paragraph\">Nach der Inbetriebnahme:<\/p>    <ul class=\"wp-block-list\"> <li>Gel\u00f6ste F\u00fctterungsherausforderungen in power-armen Gebieten<\/li>    <li>Verbesserte Silageausnutzung<\/li>    <li>Reduzierte manuelle Futterkosten<\/li> <\/ul>    <p class=\"wp-block-paragraph\">Der Kunde plant, bei der Erweiterung des Betriebs in Zukunft gr\u00f6\u00dfere vertikale TMR-Futtermischer zu kaufen.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/6cbm-trailer-vertical-tmr-mixer-for-cattle-farm.webp\" alt=\"6 cbm Anh\u00e4nger-vertikaler TMR-Mischer f\u00fcr Rinderbetrieb\" class=\"wp-image-11742\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/6cbm-trailer-vertical-tmr-mixer-for-cattle-farm.webp 720w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/6cbm-trailer-vertical-tmr-mixer-for-cattle-farm-600x450.webp 600w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/6cbm-trailer-vertical-tmr-mixer-for-cattle-farm-300x225.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/6cbm-trailer-vertical-tmr-mixer-for-cattle-farm-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">6 cbm Anh\u00e4nger-vertikaler TMR-Mischer f\u00fcr Rinderbetrieb<\/figcaption><\/figure> <\/div>   <p class=\"wp-block-paragraph translation-block\"><strong>Elektrischer vertikaler TMR-Mischer f\u00fcr gro\u00dfe Milchviehbetriebe in Thailand<\/strong><\/p>    <p class=\"wp-block-paragraph\">Der thail\u00e4ndische Kunde betreibt einen expandierenden Milchviehbetrieb mit einer Herde von \u00fcber 500 Tieren. Aufgrund einer stabilen Stromversorgung in bestimmten lokalen Gebieten entschied sich der Kunde f\u00fcr einen elektrischen TMR-Mischer.<\/p>    <p class=\"wp-block-paragraph\">Wir haben einen 20 m\u00b3 vertikalen TMR-Silage-Mischer f\u00fcr sie angepasst, wobei wir die Klingenstruktur basierend auf ihrem Mais-Silage-Anteil modifizierten. Bei der Lieferung haben wir eine Ferninstallationsanleitung bereitgestellt, um ein standardisiertes TMR-F\u00fctterungssystem zu etablieren.<\/p>    <p class=\"wp-block-paragraph\">Kundenfeedback:<\/p>    <ul class=\"wp-block-list\"> <li>Gleichm\u00e4\u00dfigere Silagemischung<\/li>    <li>Deutliche Reduktion des selektiven Essverhaltens bei Rindern<\/li>    <li>30% Verbesserung der t\u00e4glichen F\u00fctterungseffizienz<\/li> <\/ul>    <figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11729\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-wagon.webp\" alt=\"Silageballenpresse &amp; Strohballenpresse &amp; Grasm\u00e4her\" class=\"wp-image-11729\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-wagon.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-wagon-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-feed-mixer-wagon-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">20 cbm TMR-Futtermischwagen<\/figcaption><\/figure>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" data-id=\"11735\" src=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-silage-feed-mixer.webp\" alt=\"20cbm TMR Silagefuttermischer\" class=\"wp-image-11735\" title=\"\" srcset=\"https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-silage-feed-mixer.webp 540w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-silage-feed-mixer-300x300.webp 300w, https:\/\/silagebaler.com\/wp-content\/uploads\/2026\/02\/20cbm-tmr-silage-feed-mixer-12x12.webp 12w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">20Cbm TMR Silagefuttermischer<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\"><strong>FAQ zum vertikalen TMR-Mischer<\/strong><\/h2>   <div id=\"rank-math-faq\" class=\"rank-math-block\"> <div class=\"rank-math-list\"> <div id=\"faq-question-1770798901639\" class=\"rank-math-list-item\"> <h3 class=\"rank-math-question\">Was ist der Unterschied zwischen vertikalem und horizontalem Futtermischer?\ufffc<\/h3> <div class=\"rank-math-answer\">  <p>Vertikale Modelle eignen sich besser f\u00fcr das Zerkleinern von Silage und sind kosteng\u00fcnstiger.<br \/>Horizontalmischer erreichen schnellere Mischgeschwindigkeiten, erfordern jedoch eine h\u00f6here Anfangsinvestition.<\/p>  <\/div> <\/div> <div id=\"faq-question-1770798921365\" class=\"rank-math-list-item\"> <h3 class=\"rank-math-question\">Kann es nasse Silage mischen?\ufffc<\/h3> <div class=\"rank-math-answer\">  <p>Ja, die Ausr\u00fcstung ist speziell f\u00fcr nasse Silage ausgelegt.<\/p>  <\/div> <\/div> <div id=\"faq-question-1770798936787\" class=\"rank-math-list-item\"> <h3 class=\"rank-math-question\">Wie lange dauert die Mischzeit?\ufffc<\/h3> <div class=\"rank-math-answer\">  <p>Typischerweise 5\u201315 Minuten, abh\u00e4ngig von den Materialbedingungen.<\/p>  <\/div> <\/div> <div id=\"faq-question-1770798948085\" class=\"rank-math-list-item\"> <h3 class=\"rank-math-question\">Unterst\u00fctzen Sie eine kundenspezifische Spannung?\ufffc<\/h3> <div class=\"rank-math-answer\">  <p>Wir unterst\u00fctzen die Anpassung der globalen Spannung.<\/p>  <\/div> <\/div> <div id=\"faq-question-1770798957814\" class=\"rank-math-list-item\"> <h3 class=\"rank-math-question\">Was kostet der TMR-Mischer?\ufffc<\/h3> <div class=\"rank-math-answer\">  <p>Preise variieren je nach Kapazit\u00e4t, Leistungstyp und Konfiguration. F\u00fcr ein detailliertes Angebot bitte anfragen.<\/p>  <\/div> <\/div> <\/div> <\/div>   <hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>    <p class=\"wp-block-paragraph translation-block\">Wenn Sie nach einem zuverl\u00e4ssigen <strong>vertikalen TMR-Mischer<\/strong> f\u00fcr Ihren Milch- oder Rinderbetrieb suchen, kontaktieren Sie uns noch heute f\u00fcr eine Kapazit\u00e4tsberatung und das beste Angebot.<\/p>    <div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"> <div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"> <figure class=\"wp-block-embed is-type-wp-embed is-provider-silage-baler-wrapper-machine-manufacturer-taizy-agro-machinery wp-block-embed-silage-baler-wrapper-machine-manufacturer-taizy-agro-machinery\"><div class=\"wp-block-embed__wrapper\"> <blockquote class=\"wp-embedded-content\" data-secret=\"NpBoPlGT9o\"><a href=\"https:\/\/silagebaler.com\/de\/diesel-tmr-feed-mixing-and-spreading-car\/\">Diesel-TMR-Futtermisch- und Verteilwagen<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"Zapfwellen-Silage-Streumaschine\" src=\"https:\/\/silagebaler.com\/diesel-tmr-feed-mixing-and-spreading-car\/embed\/#?secret=wkEPSlIlD2#?secret=NpBoPlGT9o\" data-secret=\"NpBoPlGT9o\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe> <\/div><\/figure> <\/div>    <div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"> <figure class=\"wp-block-embed is-type-wp-embed is-provider-silage-baler-wrapper-machine-manufacturer-taizy-agro-machinery wp-block-embed-silage-baler-wrapper-machine-manufacturer-taizy-agro-machinery\"><div class=\"wp-block-embed__wrapper\"> <blockquote class=\"wp-embedded-content\" data-secret=\"GsHoQrQueC\"><a href=\"https:\/\/silagebaler.com\/de\/pto-silage-spreader-machine\/\">PTO-Silageverteiler-Maschine<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"Vertikaler TMR-Mischer\" src=\"https:\/\/silagebaler.com\/pto-silage-spreader-machine\/embed\/#?secret=8xNT5R0kgm#?secret=GsHoQrQueC\" data-secret=\"GsHoQrQueC\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe> <\/div><\/figure> <\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>Vertical TMR mixer can efficiently mix silage, hay, straw, and concentrate feed with 3\u201336m\u00b3 for dairy &#038; cattle farms. Available in electric, PTO, diesel &#038; hydraulic types. Ideal silage mixer machine.<\/p>","protected":false},"author":1,"featured_media":11709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,150],"tags":[811],"class_list":["post-11658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product","category-feed-mixer-spreader","tag-silage-feed"],"_links":{"self":[{"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/posts\/11658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/comments?post=11658"}],"version-history":[{"count":56,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/posts\/11658\/revisions"}],"predecessor-version":[{"id":11743,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/posts\/11658\/revisions\/11743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/media\/11709"}],"wp:attachment":[{"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/media?parent=11658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/categories?post=11658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silagebaler.com\/de\/wp-json\/wp\/v2\/tags?post=11658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}